{"id":16650,"date":"2025-04-03T15:07:08","date_gmt":"2025-04-03T15:07:08","guid":{"rendered":"https:\/\/www.hsli.org\/newsletter\/?page_id=16650"},"modified":"2025-12-11T19:42:23","modified_gmt":"2025-12-11T19:42:23","slug":"awards","status":"publish","type":"page","link":"https:\/\/www.hsli.org\/newsletter\/awards\/","title":{"rendered":"Awards"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Starfish Thrower Award<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">The Starfish Thrower Award is presented to an HSLI member who made a difference to the organization. The winner receives a trophy and is honored at the Awards Ceremony held during the Annual Conference in the fall.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/hsli.org\/awards\/star-thrower_award_p_and_p.pdf\">Guidelines<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/hsli.org\/newsletter\/wp-content\/uploads\/2023\/07\/starfishthrowerawardform.pdf\">Nomination Form<\/a><\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">Past Awardees<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Fran Kovach, 2000<\/li>\n\n\n\n<li>Stacey Knight-Davis, 2008<\/li>\n\n\n\n<li>Jerry DeWitt, 2012<\/li>\n\n\n\n<li>Roy Jones and Deborah Rhue, 2013<\/li>\n\n\n\n<li>Eric Edwards, 2014<\/li>\n\n\n\n<li>Stacey Knight-Davis, 2016<\/li>\n\n\n\n<li>Linda Feinberg, 2017<\/li>\n\n\n\n<li>Laura Wimmer, 2022<\/li>\n\n\n\n<li>Jonna Peterson, 2023<\/li>\n\n\n\n<li>Frances Drone-Silvers, 2024<\/li>\n\n\n\n<li>Deborah Lauseng, 2025<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">President\u2019s Award<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">The HSLI President\u2019s Award is presented by the President to an HSLI member in recognition of significant service to HSLI. The recipient is selected by the President.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Past Awardees<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Rhona Kelly, 2000<\/li>\n\n\n\n<li>Mary Ann Huslig, 2006<\/li>\n\n\n\n<li>Virginia Gale, 2008<\/li>\n\n\n\n<li>Jo Dorsch, 2011<\/li>\n\n\n\n<li>Stacey Knight-Davis, 2022<\/li>\n\n\n\n<li>Roy Jones, 2023<\/li>\n\n\n\n<li>Molly Horio, 2024<\/li>\n\n\n\n<li>Eric Edwards, 2025<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">The Syed Maghrabi Scholarship<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Syed Maghrabi, a dedicated member of HSLI, was born February 17, 1945 in Aurungabad, India. He immigrated to the USA in November 1968. Syed worked at Louis Weiss Memorial Hospital in Chicago. He received the Pride Handelman Award from Weiss Hospital in 1995, which was a source of great pride and satisfaction to him. He died on July 29, 2000. The Syed Maghrabi Scholarship was created in his honor, and it supports HSLI members\u2019 participation in the HSLI Annual Conference.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The form is generally posted two months before the annual fall conference. The form is linked from the&nbsp;<a href=\"https:\/\/www.hsli.org\/newsletter\/conference\/\">Conference Website<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Past Awardees<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Gennye Varvel, 2001<\/li>\n\n\n\n<li>Neera Kukreja, 2001<\/li>\n\n\n\n<li>Mary Ann Christopher, 2002<\/li>\n\n\n\n<li>Marci Doranski, 2002<\/li>\n\n\n\n<li>Lynne Ferrell, 2002<\/li>\n\n\n\n<li>Kristine Hughes, 2003<\/li>\n\n\n\n<li>Roberta Craig, 2003<\/li>\n\n\n\n<li>Richard McGowan, 2003<\/li>\n\n\n\n<li>Anne Heimann, 2003<\/li>\n\n\n\n<li>Laura Brosamer, 2004<\/li>\n\n\n\n<li>Lucy Webb, 2004<\/li>\n\n\n\n<li>Morgann Thomas, 2004<\/li>\n\n\n\n<li>Elissa Cochran, 2004<\/li>\n\n\n\n<li>Kristina Howard, 2004<\/li>\n\n\n\n<li>Janet Gayle, 2004<\/li>\n\n\n\n<li>Carol Jeull, 2004<\/li>\n\n\n\n<li>Cleo Pappas, 2005<\/li>\n\n\n\n<li>Kristine Hughes, 2005<\/li>\n\n\n\n<li>Melissa Hudak, 2005<\/li>\n\n\n\n<li>Peg Burnette, 2005<\/li>\n\n\n\n<li>Katie Pozniak, 2006<\/li>\n\n\n\n<li>Darlene Ward, 2006<\/li>\n\n\n\n<li>Laura Sklansky, 2008<\/li>\n\n\n\n<li>Irene Williams, 2009<\/li>\n\n\n\n<li>Clare Bonnema , 2010<\/li>\n\n\n\n<li>Erin Moore, 2010<\/li>\n\n\n\n<li>Karly Vesely, 2010<\/li>\n\n\n\n<li>Karen Douglas, 2011<\/li>\n\n\n\n<li>Eric A. Edwards, 2011<\/li>\n\n\n\n<li>Carol Jeull, 2011<\/li>\n\n\n\n<li>Clare Bonnema, 2012<\/li>\n\n\n\n<li>Elissa Cochran, 2012<\/li>\n\n\n\n<li>Sarah Isaacs, 2012<\/li>\n\n\n\n<li>Linda Feinberg, 2013<\/li>\n\n\n\n<li>Virginia Gale, 2013<\/li>\n\n\n\n<li>Carmen Howard, 2013<\/li>\n\n\n\n<li>Leslie Menz, 2013<\/li>\n\n\n\n<li>Daneen RIchardson, 2013<\/li>\n\n\n\n<li>Michael Wold, 2013<\/li>\n\n\n\n<li>Eric Edwards, 2014<\/li>\n\n\n\n<li>Lynne Ferrell, 2014<\/li>\n\n\n\n<li>Eric Edwards, 2016<\/li>\n\n\n\n<li>Stacey Knight-Davis, 2016<\/li>\n\n\n\n<li>Michelle Nielsen Ott, 2017<\/li>\n\n\n\n<li>Daneen Richardson, 2017<\/li>\n\n\n\n<li>Ann Zettervall, 2017<\/li>\n\n\n\n<li>Evelyn Cunico, 2018<\/li>\n\n\n\n<li>Kirstin Duffin, 2018<\/li>\n\n\n\n<li>Stacey Knight-Davis, 2018<\/li>\n\n\n\n<li>Daneen Richardson, 2018<\/li>\n\n\n\n<li>Betsy Sterner, 2019<\/li>\n\n\n\n<li>Amber Burtis, 2023<\/li>\n\n\n\n<li>Jaedyn Maltimore, 2025<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>Starfish Thrower Award The Starfish Thrower Award is presented to an HSLI member who made a difference to the organization. The winner receives a trophy and is honored at the Awards Ceremony held during the Annual Conference in the fall. Past Awardees President\u2019s Award The HSLI President\u2019s Award is presented by the President to an&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-16650","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.hsli.org\/newsletter\/wp-json\/wp\/v2\/pages\/16650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.hsli.org\/newsletter\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.hsli.org\/newsletter\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.hsli.org\/newsletter\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.hsli.org\/newsletter\/wp-json\/wp\/v2\/comments?post=16650"}],"version-history":[{"count":5,"href":"https:\/\/www.hsli.org\/newsletter\/wp-json\/wp\/v2\/pages\/16650\/revisions"}],"predecessor-version":[{"id":18405,"href":"https:\/\/www.hsli.org\/newsletter\/wp-json\/wp\/v2\/pages\/16650\/revisions\/18405"}],"wp:attachment":[{"href":"https:\/\/www.hsli.org\/newsletter\/wp-json\/wp\/v2\/media?parent=16650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}